{"id":71375,"date":"2025-01-27T13:22:54","date_gmt":"2025-01-27T16:22:54","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71375"},"modified":"2025-01-27T13:22:56","modified_gmt":"2025-01-27T16:22:56","slug":"rede-de-farmacias-sao-joao-realiza-palestra-com-o-tema-saude-mental-no-mundo-digital","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/rede-de-farmacias-sao-joao-realiza-palestra-com-o-tema-saude-mental-no-mundo-digital\/","title":{"rendered":"Rede de Farm\u00e1cias S\u00e3o Jo\u00e3o realiza palestra com o tema: sa\u00fade mental no mundo digital"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"x_MsoNormal\" style=\"text-align: center;\"><i data-olk-copy-source=\"MessageBody\">Evento fez parte das a\u00e7\u00f5es promovidas no janeiro branco, dentro do Ciclo de palestras da Rede S\u00e3o Jo\u00e3o para a promo\u00e7\u00e3o da sa\u00fade aos seus colaboradores.<\/i><\/p>\n<p class=\"x_MsoNormal\" aria-hidden=\"true\">\u00a0<\/p>\n<p class=\"x_MsoNormal\">Com o audit\u00f3rio de Passo Fundo lotado de colaboradores do administrativo do Centro de Opera\u00e7\u00f5es e Distribui\u00e7\u00e3o e a participa\u00e7\u00e3o online de coordenadores distritais e regionais, mais os trabalhadores do Centro de Distribui\u00e7\u00e3o em Gravata\u00ed, a\u00a0<a title=\"https:\/\/www.saojoaofarmacias.com.br\/\" href=\"https:\/\/www.saojoaofarmacias.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\" data-linkindex=\"0\">Rede de Farm\u00e1cias S\u00e3o Jo\u00e3o<\/a>\u00a0realizou nesta segunda-feira (27) mais uma edi\u00e7\u00e3o do evento Ciclo de Palestras,\u00a0<b>Conex\u00e3o S\u00e3o Jo\u00e3o: Saber e Cuidar<\/b>\u00a0que busca promover conhecimento e sa\u00fade aos colaboradores da empresa.<\/p>\n<p class=\"x_MsoNormal\">Para falar sobre sa\u00fade mental no mundo digital dentro das celebra\u00e7\u00f5es do\u00a0<b><i>Janeiro Branco<\/i><\/b>, m\u00eas dedicado \u00e0 promo\u00e7\u00e3o da sa\u00fade emocional e mental da popula\u00e7\u00e3o, a empresa parou suas atividades administrativas pela manh\u00e3 para trazer reflex\u00f5es sobre as emo\u00e7\u00f5es humanas e como ter um relacionamento mais saud\u00e1vel consigo e com o pr\u00f3ximo.<\/p>\n<p class=\"x_MsoNormal\">Foram convidados os m\u00e9dicos Carlos Roberto Hecktheuer, psiquiatra com 58 anos de experi\u00eancia, doutor pela Cl\u00ednica Pinel, psicanalista pela ABP (Associa\u00e7\u00e3o Psicanal\u00edtica Brasileira) e fundador do Centro Comunit\u00e1rio de Sa\u00fade Mental de Passo Fundo e Erico Ramos Hecktheuer, m\u00e9dico pela UFPEL (Universidade Federal de Pelotas), psiquiatra pela ABP (Associa\u00e7\u00e3o Brasileira de Psiquiatria), psicoterapeuta pelo CEF (Centro de Estudos da Fam\u00edlia), Instituto WP (Wainer e Picolotto) e Sociedade Cient\u00edfica Sigmund Freud. Al\u00e9m de psiquiatra com 34 anos de experi\u00eancia, Erico tamb\u00e9m \u00e9 apresentador do Programa Emo\u00e7\u00e3o Afeto e Comportamento na R\u00e1dio Uirapuru em Passo Fundo, no ar h\u00e1 13 anos.<\/p>\n<div id=\"attachment_71377\" style=\"width: 410px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-71377\" class=\"wp-image-71377 size-medium\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/71-2-400x393.jpg\" alt=\"\" width=\"400\" height=\"393\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/71-2-400x393.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/71-2-768x755.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/71-2-1536x1510.jpg 1536w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/01\/71-2-2048x2013.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><p id=\"caption-attachment-71377\" class=\"wp-caption-text\">Erico Hecktheuer, Pedro Henrique Brair e Carlos Roberto Hecktheuer<\/p><\/div>\n<p class=\"x_MsoNormal\">\u201c<em>A gente trouxe um pouco da nossa experi\u00eancia, do que a gente acha relevante sobre sa\u00fade mental no mundo digital. Os colaboradores fizeram perguntas pertinentes e isso me fez sair daqui satisfeito, com a ideia de que pudemos colaborar trazendo reflex\u00f5es, questionamentos, com o intuito de que as pessoas possam viver melhor e quem sabe, aprenderem a simplificar a vida,<\/em>\u201d destacou Erico Hecktheuer.<\/p>\n<p class=\"x_MsoNormal\">O programa\u00a0<b>Ciclo de Palestras<\/b>\u00a0\u00e9 um evento que traz profissionais para tratar de temas importantes para o desenvolvimento profissional e humano de seus colaboradores. A palestra foi assistida por mais de 600 colaboradores da Rede S\u00e3o Jo\u00e3o em Passo Fundo, Gravata\u00ed e coordenadores do Rio Grande do Sul, Santa Catarina e Paran\u00e1.<\/p>\n<hr \/>\n<h6 class=\"x_MsoNormal\" aria-hidden=\"true\"><strong>Rede de Farm\u00e1cias S\u00e3o Jo\u00e3o<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Evento fez parte das a\u00e7\u00f5es promovidas no janeiro branco, dentro do Ciclo de palestras da Rede S\u00e3o Jo\u00e3o para a promo\u00e7\u00e3o da sa\u00fade aos seus colaboradores. \u00a0 Com o audit\u00f3rio de Passo Fundo lotado de colaboradores do administrativo do Centro de Opera\u00e7\u00f5es e Distribui\u00e7\u00e3o e a participa\u00e7\u00e3o online de coordenadores distritais e regionais, mais os [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71376,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71375"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71375\/revisions"}],"predecessor-version":[{"id":71378,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71375\/revisions\/71378"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71376"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}