{"id":71472,"date":"2025-01-31T22:18:07","date_gmt":"2025-02-01T01:18:07","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71472"},"modified":"2025-01-31T22:18:08","modified_gmt":"2025-02-01T01:18:08","slug":"mundial-braford-prepara-abertura-de-inscricoes-de-animais","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/mundial-braford-prepara-abertura-de-inscricoes-de-animais\/","title":{"rendered":"Mundial Braford prepara abertura de inscri\u00e7\u00f5es de animais"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Para o evento promovido pela ABHB s\u00e3o esperados criadores do Brasil, Argentina, Paraguai, Uruguai, Estados Unidos, Austr\u00e1lia, entre outros<\/em><\/p>\n<p>O 9\u00ba Congresso Mundial Braford, que acontecer\u00e1 de 28 de abril a 4 de maio de 2025 no Parque de Exposi\u00e7\u00f5es Assis Brasil, em Esteio (RS), ter\u00e1 programa\u00e7\u00e3o diversificada, incluindo uma gira t\u00e9cnica por fazendas em Ma\u00e7ambar\u00e1, Uruguaiana, Sant'Ana do Livramento e Arambar\u00e9, palestras e julgamentos. Com jurados renomados como Ciro Manoel Canto de Freitas e Celina Maciel, al\u00e9m do \u00e1rbitro Paulo Azambuja, o evento espera receber criadores e produtores de diversos pa\u00edses, como Argentina, Paraguai, Uruguai, Estados Unidos, Austr\u00e1lia, entre outros, para fomentar o interc\u00e2mbio de conhecimento e neg\u00f3cios em torno da ra\u00e7a Braford.<\/p>\n<p>Em fase de organiza\u00e7\u00e3o bem adiantada, os organizadores anunciam que em breve ser\u00e3o abertas as inscri\u00e7\u00f5es de animais. O gerente executivo da Associa\u00e7\u00e3o Brasileira de Hereford e Braford (ABHB), Felipe Azambuja, destaca que a expectativa \u00e9 de recorde de inscri\u00e7\u00f5es de animais, tanto para os julgamentos da ra\u00e7a Braford quanto para a 18\u00aa Exposi\u00e7\u00e3o Nacional da ra\u00e7a Hereford, estimada pela entidade como a maior de todos os tempos.<\/p>\n<p>Quanto aos preparativos para a Gira T\u00e9cnica por fazendas no interior do Estado, Azambuja conta que as visitas preparat\u00f3rias ser\u00e3o em tr\u00eas fases. \u201c<em>J\u00e1 fizemos duas etapas de visita, a primeira para defini\u00e7\u00e3o de modelo de trabalho e a segunda para preparar a parte de comunica\u00e7\u00e3o visual e projetos de cada est\u00e2ncia onde ir\u00e3o ocorrer as programa\u00e7\u00f5es e o p\u00fablico ser\u00e1 recebido. Em breve queremos a terceira, que \u00e9 j\u00e1 com a sele\u00e7\u00e3o de animais que ser\u00e3o apresentados dentro das propriedades<\/em>\u201d, detalha. E com rela\u00e7\u00e3o \u00e0 segunda etapa do Mundial, Azambuja relata que a entidade visitou o parque, em Esteio, para avaliar como est\u00e1 o andamento das a\u00e7\u00f5es operacionais, que contam com a parceria da Farsul e do governo do Estado atrav\u00e9s da subsecretaria do Parque.<br \/><br \/>O gestor destaca, ainda, a parceria com a Associa\u00e7\u00e3o Brasileira de Criadores de Cavalos Crioulos (ABCCC). Durante o Mundial estar\u00e1 acontecendo, de forma paralela, o Bocal de Ouro. A ABHB e a ABCCC est\u00e3o alinhando atividades para que um evento seja apoiado pelo outro.<\/p>\n<p>Esta \u00e9 a segunda vez que o Brasil recebe o Mundial Braford. A primeira ocorreu em 2000, na cidade de Uruguaiana (RS). O Congresso Mundial Braford acontece a cada tr\u00eas anos. J\u00e1 foi realizado em pa\u00edses como Argentina, Paraguai, Uruguai, Austr\u00e1lia e Estados Unidos. Al\u00e9m da Gira T\u00e9cnica que vai percorrer mais de 800 quil\u00f4metros dentro do Rio Grande do Sul, o Mundial ter\u00e1, na sua programa\u00e7\u00e3o, palestras, eventos gastron\u00f4micos, entre outros.<\/p>\n<hr \/>\n<h6><strong>AgroEffective | Assessoria de Comunica\u00e7\u00e3o da Associa\u00e7\u00e3o Brasileira de Hereford e Braford (ABHB) | <span style=\"font-size: revert; color: initial;\">Foto: Gustavo Rafael\/Divulga\u00e7\u00e3o |\u00a0<\/span>Texto: Ieda Risco\/AgroEffective<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Para o evento promovido pela ABHB s\u00e3o esperados criadores do Brasil, Argentina, Paraguai, Uruguai, Estados Unidos, Austr\u00e1lia, entre outros O 9\u00ba Congresso Mundial Braford, que acontecer\u00e1 de 28 de abril a 4 de maio de 2025 no Parque de Exposi\u00e7\u00f5es Assis Brasil, em Esteio (RS), ter\u00e1 programa\u00e7\u00e3o diversificada, incluindo uma gira t\u00e9cnica por fazendas em [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71473,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71472"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71472\/revisions"}],"predecessor-version":[{"id":71474,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71472\/revisions\/71474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71473"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}