{"id":71617,"date":"2025-02-06T10:40:27","date_gmt":"2025-02-06T13:40:27","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71617"},"modified":"2025-02-06T10:40:28","modified_gmt":"2025-02-06T13:40:28","slug":"governador-assina-termos-de-cooperacao-do-desassorear-rs-com-municipios-no-vale-do-taquari","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governador-assina-termos-de-cooperacao-do-desassorear-rs-com-municipios-no-vale-do-taquari\/","title":{"rendered":"Governador assina termos de coopera\u00e7\u00e3o do Desassorear RS com munic\u00edpios no Vale do Taquari"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Leite tamb\u00e9m entregou a primeira etapa dos Planos Diretores para sete munic\u00edpios<\/em><\/p>\n<p>Durante extensa agenda no Vale do Taquari nesta quarta-feira (5\/2), o governador Eduardo Leite assinou termos de coopera\u00e7\u00e3o do programa Desassorear RS com 26 munic\u00edpios da regi\u00e3o. O ato de assinatura foi realizado na cidade de Estrela, com a participa\u00e7\u00e3o dos titulares da Secretaria de Desenvolvimento Urbano e Metropolitano (Sedur), Rafael Mallmann, da Secretaria de Habita\u00e7\u00e3o e Regulariza\u00e7\u00e3o Fundi\u00e1ria (Sehab), Carlos Gomes, e da Secretaria de Planejamento, Governan\u00e7a e Gest\u00e3o (SPGG), Danielle Calazans. O investimento em obras de desassoreamento nestes munic\u00edpios ser\u00e1 de quase R$ 40 milh\u00f5es.<\/p>\n<p>As assinaturas ocorreram uma semana depois do governador anunciar os 154 munic\u00edpios contemplados pelo programa. No total, o investimento no Desassorear RS ser\u00e1 de R$ 300 milh\u00f5es em contrata\u00e7\u00e3o de maquin\u00e1rio para a limpeza de arroios, canais de drenagem e sistemas pluviais.<\/p>\n<p>O governador disse que os munic\u00edpios apontaram os pontos cr\u00edticos que necessitavam do processo de desassoreamento e o Estado entrou com o investimento. \u201c<em>J\u00e1 s\u00e3o oito frentes de trabalho implantadas da semana passada para c\u00e1, e vamos chegar a 40 frentes de trabalho simult\u00e2neas para cumprir o mais rapidamente poss\u00edvel com essa etapa dos 154 munic\u00edpios que apresentaram projetos, ajudando essas localidades a melhorarem o fluxo dos cursos d'\u00e1gua, passando a oferecer menos riscos para as suas comunidades\u201d<\/em>, destacou Leite.<\/p>\n<p>O titular da Sedur ressaltou o desassoreamento como uma a\u00e7\u00e3o que faz parte da prepara\u00e7\u00e3o das cidades para novos eventos meteorol\u00f3gicos. <em>\u201cFaz parte de um trabalho de resili\u00eancia clim\u00e1tica nos munic\u00edpios, minimizando os impactos de poss\u00edveis enxurradas\u201d<\/em>, enfatizou Mallmann.<\/p>\n<p>Nos munic\u00edpios de Encantado, Estrela, Colinas, Roca Sales, Mu\u00e7um, Arroio do Meio e Cruzeiro do Sul, tamb\u00e9m foi realizada a entrega da primeira etapa dos Planos Diretores de Desenvolvimento Urbano (PDDUs), que s\u00e3o elaborados pela Sedur em parceria com a Universidade do Vale do Taquari (Univates). Os Planos Diretores contemplam as novas diretrizes de uso do solo, constru\u00e7\u00e3o e infraestrutura que consideram as vulnerabilidades espec\u00edficas de cada munic\u00edpio, sobretudo no atual contexto de emerg\u00eancia clim\u00e1tica.<\/p>\n<p><strong>Loteamentos vistoriados<\/strong><\/p>\n<p>Al\u00e9m do Desassorear e dos Planos Diretores, a Sedur \u00e9 respons\u00e1vel pelo programa horas-m\u00e1quina em \u00e1rea urbanas, atuando na infraestrutura dos loteamentos, trabalhando com a limpeza dos terrenos, nivelamento de lotes e abertura de vias, entre outras a\u00e7\u00f5es necess\u00e1rias para realoca\u00e7\u00e3o e implanta\u00e7\u00e3o de resid\u00eancias.\u00a0<\/p>\n<div id=\"attachment_71619\" style=\"width: 410px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-71619\" class=\"wp-image-71619 size-medium\" src=\"http:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/02\/61-400x266.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/02\/61-400x266.jpg 400w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/02\/61-768x511.jpg 768w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/02\/61-600x400.jpg 600w, https:\/\/sol.fm.br\/radio\/wp-content\/uploads\/2025\/02\/61.jpg 945w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><p id=\"caption-attachment-71619\" class=\"wp-caption-text\">Foto: Maur\u00edcio Tonetto\/Secom<\/p><\/div>\n<p>A comitiva do governo do Estado, acompanhada de prefeitos e outras lideran\u00e7as,\u00a0<a href=\"https:\/\/estado.rs.gov.br\/leite-visita-construcao-das-primeiras-casas-definitivas-para-atingidos-por-enchentes-no-vale-do-taquari\" target=\"_blank\" rel=\"noopener\"><strong>vistoriou loteamentos que est\u00e3o recebendo investimentos de horas-m\u00e1quina nas cidades de Santa Tereza, Mu\u00e7um, Estrela, Lajeado e Cruzeiro do Sul<\/strong><\/a>.<\/p>\n<p>Os munic\u00edpios apresentaram pontos cr\u00edticos que precisavam de limpeza dos rios e o Estado contratou o maquin\u00e1rio que est\u00e1 entrando em campo agora em 40 frentes simult\u00e2neas.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Paulo C\u00e9sar Pedroza e Felipe Fontoura\/Ascom\/Sedur e Thamiris Mondin\/Secom | Edi\u00e7\u00e3o: Camila Cargnelutti\/Secom | Foto: Vitor Rosa\/Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Leite tamb\u00e9m entregou a primeira etapa dos Planos Diretores para sete munic\u00edpios Durante extensa agenda no Vale do Taquari nesta quarta-feira (5\/2), o governador Eduardo Leite assinou termos de coopera\u00e7\u00e3o do programa Desassorear RS com 26 munic\u00edpios da regi\u00e3o. O ato de assinatura foi realizado na cidade de Estrela, com a participa\u00e7\u00e3o dos titulares da [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71617"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71617\/revisions"}],"predecessor-version":[{"id":71620,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71617\/revisions\/71620"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71618"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}