{"id":71699,"date":"2025-02-11T09:21:29","date_gmt":"2025-02-11T12:21:29","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71699"},"modified":"2025-02-11T09:21:31","modified_gmt":"2025-02-11T12:21:31","slug":"grupo-empresarial-que-atua-no-ramo-de-bebidas-tem-r-74-milhoes-bloqueados-apos-operacao-do-cira-rs","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/grupo-empresarial-que-atua-no-ramo-de-bebidas-tem-r-74-milhoes-bloqueados-apos-operacao-do-cira-rs\/","title":{"rendered":"Grupo empresarial que atua no ramo de bebidas tem R$ 7,4 milh\u00f5es bloqueados ap\u00f3s opera\u00e7\u00e3o do Cira\/RS"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Do valor bloqueado, s\u00e3o R$ 6,3 milh\u00f5es na esfera criminal e cerca de R$ 1,1 milh\u00e3o na esfera c\u00edvel<\/em><\/p>\n<p>Depois de deflagrar em 23 de janeiro deste ano em tr\u00eas cidades ga\u00fachas a Opera\u00e7\u00e3o Triplo Malte contra uma ind\u00fastria de bebidas que teria sonegado R$ 200 milh\u00f5es dos cofres p\u00fablicos, o Comit\u00ea Interinstitucional de Recupera\u00e7\u00e3o de Ativos do Estado do Rio Grande do Sul (Cira\/RS) conseguiu obter o bloqueio judicial de R$ 7,4 milh\u00f5es do grupo empresarial respons\u00e1vel, que atua tamb\u00e9m em outros ramos de neg\u00f3cios. S\u00e3o R$ 6,3 milh\u00f5es na esfera criminal e cerca de R$ 1,1 milh\u00e3o na esfera c\u00edvel.<\/p>\n<p>A opera\u00e7\u00e3o foi realizada em Porto Alegre, Torres e Santa Maria pelo Grupo de Atua\u00e7\u00e3o Especial de Combate ao Crime Organizado (Gaeco) do Minist\u00e9rio P\u00fablico do Rio Grande do Sul (MPRS), pela Procuradoria-Geral do Estado (PGE\/RS) e pela Secretaria da Fazenda (Sefaz), por meio da Receita Estadual, todas institui\u00e7\u00f5es que integram o Cira\/RS. Na ocasi\u00e3o, foram cumpridos 14 mandados de busca e apreens\u00e3o em empresas e resid\u00eancias. A d\u00edvida tribut\u00e1ria dos investigados \u00e9 uma das cinco maiores do Estado.<\/p>\n<p>Em rela\u00e7\u00e3o aos bloqueios, eles foram decretados pelo Poder Judici\u00e1rio, ap\u00f3s apreciar medida assecurat\u00f3ria de sequestro ajuizada pelo MPRS, no \u00e2mbito criminal, e medida cautelar fiscal ajuizada pela PGE\/RS. A investiga\u00e7\u00e3o ocorreu por meio de procedimento instaurado pela Promotoria de Justi\u00e7a Especializada Criminal de Porto Alegre \u2013 Combate aos Crimes contra a Ordem Tribut\u00e1ria, ap\u00f3s o encaminhamento pela Receita Estadual de relat\u00f3rio apontando a exist\u00eancia de diversas empresas com ind\u00edcios de atua\u00e7\u00e3o coordenada e de confus\u00e3o patrimonial. Foi constatado que os preju\u00edzos foram decorrentes de il\u00edcitos fiscais por meio de sonega\u00e7\u00e3o de Imposto sobre Circula\u00e7\u00e3o de Mercadorias e servi\u00e7os (ICMS) e n\u00e3o recolhimento doloso e contumaz do imposto estadual declarado.<\/p>\n<p><strong>Cira\/RS<\/strong><\/p>\n<p>O Comit\u00ea Interinstitucional de Recupera\u00e7\u00e3o de Ativos do Estado do Rio Grande do Sul \u00e9 composto pelo MPRS, por meio do Gaeco, pela Sefaz, por meio da Receita Estadual, e pela PGE\/RS. Foi institu\u00eddo pelo Decreto 54.191\/2018. O objetivo \u00e9 proporcionar a realiza\u00e7\u00e3o de a\u00e7\u00f5es conjuntas e garantir efetividade \u00e0 recupera\u00e7\u00e3o de ativos de titularidade do Estado. Para fazer den\u00fancias envolvendo sonega\u00e7\u00e3o de tributos estaduais, oculta\u00e7\u00e3o patrimonial e financeira de empresas devedoras, acesse a p\u00e1gina da Receita Estadual.<\/p>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom PGE\/Ascom Sefaz\/Ascom MPRS | Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Do valor bloqueado, s\u00e3o R$ 6,3 milh\u00f5es na esfera criminal e cerca de R$ 1,1 milh\u00e3o na esfera c\u00edvel Depois de deflagrar em 23 de janeiro deste ano em tr\u00eas cidades ga\u00fachas a Opera\u00e7\u00e3o Triplo Malte contra uma ind\u00fastria de bebidas que teria sonegado R$ 200 milh\u00f5es dos cofres p\u00fablicos, o Comit\u00ea Interinstitucional de Recupera\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71699"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71699\/revisions"}],"predecessor-version":[{"id":71701,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71699\/revisions\/71701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71700"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}