{"id":71708,"date":"2025-02-11T09:45:06","date_gmt":"2025-02-11T12:45:06","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=71708"},"modified":"2025-02-11T09:45:07","modified_gmt":"2025-02-11T12:45:07","slug":"governo-cria-condicoes-para-reformar-rede-eletrica-das-escolas-estaduais-com-mais-rapidez","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/governo-cria-condicoes-para-reformar-rede-eletrica-das-escolas-estaduais-com-mais-rapidez\/","title":{"rendered":"Governo cria condi\u00e7\u00f5es para reformar rede el\u00e9trica das escolas estaduais com mais rapidez"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p class=\"artigo__subtitulo\" style=\"text-align: center;\"><em>Desde o in\u00edcio de 2025, contrata\u00e7\u00e3o simplificada passou a valer em todo o RS, trazendo mais agilidade aos processos<\/em><\/p>\n<p>A Secretaria de Obras P\u00fablicas (SOP) implementou mudan\u00e7as em seus processos que permitem, em 2025, reformar com agilidade a rede el\u00e9trica das escolas estaduais, de acordo com a defini\u00e7\u00e3o de prioridades a partir das necessidades de cada institui\u00e7\u00e3o. Isso porque, no in\u00edcio do ano, a contrata\u00e7\u00e3o simplificada passou a valer em todo o Rio Grande do Sul, portanto, abrangendo as 2,3 mil institui\u00e7\u00f5es de ensino. Em muitas delas, a necessidade de redimensionar a parte el\u00e9trica defasada surgiu com a demanda de instala\u00e7\u00e3o de aparelhos de ar-condicionado.<\/p>\n<p>\u201c<em>Em 2023 e 2024, n\u00e3o faltaram recursos para a realiza\u00e7\u00e3o de obras nas escolas do Estado. A situa\u00e7\u00e3o permanece a mesma em 2025, com a certeza de mais agilidade nos processos, gra\u00e7as \u00e0 contrata\u00e7\u00e3o simplificada. A partir da retomada de investimentos por parte do governo, temos condi\u00e7\u00f5es de executar os servi\u00e7os, de acordo com um planejamento que estabele\u00e7a prioridades conjugadas \u00e0 capacidade de as empresas contratadas executarem os servi\u00e7os<\/em>\", afirmou a titular da SOP, Izabel Matte.<\/p>\n<p>A reforma de rede el\u00e9trica \u00e9 um processo criterioso e composto de etapas, a fim de garantir seguran\u00e7a e efici\u00eancia, de acordo com as normas t\u00e9cnicas vigentes. Ele come\u00e7a com uma vistoria t\u00e9cnica para avaliar a rede el\u00e9trica, o que d\u00e1 elementos para calcular a carga necess\u00e1ria \u00e0 instala\u00e7\u00e3o dos equipamentos de climatiza\u00e7\u00e3o.<\/p>\n<p>Os dados resultantes embasam a elabora\u00e7\u00e3o do projeto el\u00e9trico, que detalha as adequa\u00e7\u00f5es necess\u00e1rias, o que pode incluir a instala\u00e7\u00e3o de uma nova subesta\u00e7\u00e3o el\u00e9trica que suporte o aumento de carga, assim evitando sobrecargas ou quedas de energia. Conforme o projeto, s\u00e3o indicados transformadores adequados para a distribui\u00e7\u00e3o eficiente da energia. Antes de a obra come\u00e7ar, \u00e9 preciso aprovar o projeto na concession\u00e1ria de energia local.<\/p>\n<p>A execu\u00e7\u00e3o da nova infraestrutura el\u00e9trica ocorre com a instala\u00e7\u00e3o da subesta\u00e7\u00e3o, o posicionamento dos transformadores e a adapta\u00e7\u00e3o da rede interna para suportar os aparelhos de ar-condicionado.<\/p>\n<p><strong>Contrata\u00e7\u00e3o simplificada<\/strong><\/p>\n<p>A contrata\u00e7\u00e3o simplificada \u00e9 um processo que agiliza a manuten\u00e7\u00e3o das escolas. Nesse modelo, a licita\u00e7\u00e3o \u00e9 feita por blocos de escolas e h\u00e1 um \u201ccat\u00e1logo de servi\u00e7os\u201d \u00e0 disposi\u00e7\u00e3o da SOP para atender \u00e0s demandas com maior velocidade. N\u00e3o \u00e9 necess\u00e1rio licitar cada servi\u00e7o, e a escola tem uma empresa respons\u00e1vel pr\u00e9-contratada para realizar a manuten\u00e7\u00e3o. Isso acelera o processo, em compara\u00e7\u00e3o \u00e0 realiza\u00e7\u00e3o de uma licita\u00e7\u00e3o por obra, que no passado era o \u00fanico modelo poss\u00edvel.<\/p>\n<p>A implementa\u00e7\u00e3o da contrata\u00e7\u00e3o simplificada integra a recupera\u00e7\u00e3o da capacidade de investimento por parte do Estado. Nos \u00faltimos anos, o Governo do Rio Grande do Sul realizou reformas estruturantes que permitiram que se voltasse a destinar recursos para qualificar a estrutura f\u00edsica das escolas da Rede Estadual. Essas a\u00e7\u00f5es s\u00e3o fruto da determina\u00e7\u00e3o do governador Eduardo Leite, no in\u00edcio desta gest\u00e3o, de colocar a educa\u00e7\u00e3o como prioridade de seu segundo mandato.<\/p>\n<ul>\n<li><a href=\"https:\/\/estado.rs.gov.br\/governo-ja-liberou-mais-de-meio-bilhao-de-reais-para-qualificar-estrutura-das-escolas-estaduais-por-meio-do-programa-agiliza-edu\" target=\"_blank\" rel=\"noopener\"><strong>Governo j\u00e1 liberou mais de meio bilh\u00e3o de reais para qualificar estrutura das escolas por meio do Agiliza Educa\u00e7\u00e3o<\/strong><\/a><\/li>\n<\/ul>\n<hr \/>\n<h6><strong>GOV RS | Texto: Ascom SOP | Edi\u00e7\u00e3o: Secom<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Desde o in\u00edcio de 2025, contrata\u00e7\u00e3o simplificada passou a valer em todo o RS, trazendo mais agilidade aos processos A Secretaria de Obras P\u00fablicas (SOP) implementou mudan\u00e7as em seus processos que permitem, em 2025, reformar com agilidade a rede el\u00e9trica das escolas estaduais, de acordo com a defini\u00e7\u00e3o de prioridades a partir das necessidades de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":71709,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-71708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=71708"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71708\/revisions"}],"predecessor-version":[{"id":71710,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/71708\/revisions\/71710"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/71709"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=71708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=71708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=71708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}