{"id":75481,"date":"2025-06-27T10:19:50","date_gmt":"2025-06-27T13:19:50","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=75481"},"modified":"2025-06-27T10:19:52","modified_gmt":"2025-06-27T13:19:52","slug":"setcergs-recebe-com-alivio-decisao-do-congresso-que-barra-aumento-do-iof","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/setcergs-recebe-com-alivio-decisao-do-congresso-que-barra-aumento-do-iof\/","title":{"rendered":"SETCERGS recebe com al\u00edvio decis\u00e3o do Congresso que barra aumento do IOF"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><em>Derrubada de decretos que elevavam al\u00edquotas do Imposto sobre Opera\u00e7\u00f5es Financeiras representa vit\u00f3ria para o setor e preserva acesso ao cr\u00e9dito com menor custo<\/em><\/p>\n<p>O Sindicato das Empresas de Transportes de Carga e Log\u00edstica no Estado do Rio Grande do Sul (SETCERGS) recebeu com al\u00edvio e aprova\u00e7\u00e3o a decis\u00e3o do Congresso Nacional, que nesta quarta-feira (25\/06) aprovou o Projeto de Decreto Legislativo (PDL) 214\/2025, sustando os efeitos de tr\u00eas decretos presidenciais que aumentavam as al\u00edquotas do IOF (Imposto sobre Opera\u00e7\u00f5es Financeiras).<br \/><br \/>A medida \u2014 agora \u00e0 espera de promulga\u00e7\u00e3o oficial pelo Legislativo \u2014 revoga os decretos n\u00ba 12.466\/2025, n\u00ba 12.467\/2025 e n\u00ba 12.499\/2025, publicados nos meses de maio e junho, que elevaram a tributa\u00e7\u00e3o sobre empr\u00e9stimos, financiamentos, uso de cart\u00f5es de cr\u00e9dito e remessas ao exterior. Para o setor de transporte rodovi\u00e1rio de cargas, que depende amplamente de capital de giro, cr\u00e9dito banc\u00e1rio e financiamentos de frotas, a decis\u00e3o traz previsibilidade e al\u00edvio financeiro em um cen\u00e1rio de alta nos custos operacionais.<br \/><br \/>\u201c<em>A revers\u00e3o do aumento do IOF representa um avan\u00e7o importante. O impacto seria direto no caixa das empresas, especialmente as pequenas e m\u00e9dias transportadoras que utilizam financiamento como ferramenta de gest\u00e3o. Embora a decis\u00e3o j\u00e1 tenha sido aprovada, \u00e9 fundamental que as empresas fiquem atentas: os efeitos s\u00f3 ser\u00e3o aplic\u00e1veis ap\u00f3s a promulga\u00e7\u00e3o oficial do decreto legislativo\u201d<\/em>, explica o assessor jur\u00eddico do SETCERGS, Fernando Massignan.<br \/><br \/>A aprova\u00e7\u00e3o do PDL 214\/2025 aconteceu de forma simb\u00f3lica e r\u00e1pida tanto na C\u00e2mara dos Deputados quanto no Senado Federal, e representa um raro movimento de conten\u00e7\u00e3o de decretos presidenciais por parte do Congresso \u2014 mecanismo previsto na Constitui\u00e7\u00e3o, mas com baixo \u00edndice de efetiva\u00e7\u00e3o desde sua cria\u00e7\u00e3o em 1989.<br \/><br \/>O SETCERGS refor\u00e7a o seu compromisso em acompanhar de perto as movimenta\u00e7\u00f5es legislativas que afetam a gest\u00e3o financeira e tribut\u00e1ria das empresas do setor, por meio da Eixo Assessoria Institucional. Para d\u00favidas os associados podem entrar em contato com a Assessoria Jur\u00eddica do SETCERGS pelo e-mail: <a href=\"juridico@setcergs.org.br\">juridico@setcergs.org.br<\/a>.<br \/><br \/><strong>Sobre o SETCERGS<\/strong><\/p>\n<p>O Sindicato das Empresas de Transportes de Carga e Log\u00edstica no Estado do Rio Grande do Sul \u2013 SETCERGS foi fundado em agosto de 1959 e \u00e9 o \u00f3rg\u00e3o de representa\u00e7\u00e3o sindical patronal do transporte rodovi\u00e1rio de cargas com base territorial na maior parte do Estado do Rio Grande do Sul.<\/p>\n<hr \/>\n<h6><strong>PlayPress | SETCERGS - Sindicato das Empresas de Transportes de Carga e Log\u00edstica no Estado do Rio Grande do Sul | Reda\u00e7\u00e3o: Marcelo Matusiak<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Derrubada de decretos que elevavam al\u00edquotas do Imposto sobre Opera\u00e7\u00f5es Financeiras representa vit\u00f3ria para o setor e preserva acesso ao cr\u00e9dito com menor custo O Sindicato das Empresas de Transportes de Carga e Log\u00edstica no Estado do Rio Grande do Sul (SETCERGS) recebeu com al\u00edvio e aprova\u00e7\u00e3o a decis\u00e3o do Congresso Nacional, que nesta quarta-feira [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":75482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-75481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/75481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=75481"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/75481\/revisions"}],"predecessor-version":[{"id":75483,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/75481\/revisions\/75483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/75482"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=75481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=75481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=75481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}