{"id":84601,"date":"2026-05-05T21:26:24","date_gmt":"2026-05-06T00:26:24","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=84601"},"modified":"2026-05-05T21:26:28","modified_gmt":"2026-05-06T00:26:28","slug":"webmotors-moderniza-gestao-do-trabalho-hibrido-com-tecnologia-de-identidade-digital","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/webmotors-moderniza-gestao-do-trabalho-hibrido-com-tecnologia-de-identidade-digital\/","title":{"rendered":"Webmotors moderniza gest\u00e3o do trabalho h\u00edbrido com tecnologia de identidade digital"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p style=\"text-align: center;\"><i data-olk-copy-source=\"MessageBody\">Solu\u00e7\u00e3o combina dados em tempo real e credenciais m\u00f3veis para otimizar a ocupa\u00e7\u00e3o e a rotina dos colaboradores<\/i><\/p>\n<div>\n<p>Fundada h\u00e1 30 anos, a Webmotors, uma das principais plataformas digitais do setor automotivo, vem consolidando sua atua\u00e7\u00e3o na intermedia\u00e7\u00e3o de compra, venda e servi\u00e7os relacionados a ve\u00edculos. Nascida no contexto da digitaliza\u00e7\u00e3o dos classificados impressos, a empresa expandiu seu portf\u00f3lio para diferentes frentes do segmento, como financiamento, assinatura e manuten\u00e7\u00e3o, conectando atualmente mais de 34 milh\u00f5es de usu\u00e1rios por m\u00eas e figurando entre os maiores marketplaces automotivos do mundo.<\/p>\n<p>Diante da evolu\u00e7\u00e3o do modelo de trabalho h\u00edbrido e do crescimento da opera\u00e7\u00e3o, a companhia avan\u00e7ou na moderniza\u00e7\u00e3o da gest\u00e3o de seus espa\u00e7os corporativos. A iniciativa integra a plataforma de gerenciamento de workplace da Deskbee com as tecnologias de identidade segura da HID, permitindo organizar a ocupa\u00e7\u00e3o do escrit\u00f3rio de forma mais eficiente e inteligente. Com isso, a empresa passou a contar com maior visibilidade sobre a presen\u00e7a das equipes e a utiliza\u00e7\u00e3o dos espa\u00e7os, com dados atualizados em tempo real.<\/p>\n<p>Antes da implementa\u00e7\u00e3o, a gest\u00e3o da presen\u00e7a no escrit\u00f3rio era descentralizada, o que dificultava o planejamento e a previsibilidade, especialmente diante de um quadro de colaboradores distribu\u00eddos em diferentes \u00e1reas. Esse cen\u00e1rio resultava, em alguns momentos, em sobrecarga de ocupa\u00e7\u00e3o e impactava tanto a organiza\u00e7\u00e3o das equipes quanto a experi\u00eancia dos profissionais no ambiente f\u00edsico.<\/p>\n<p>\u201c<em>Temos sete diretorias, e cada uma tem seu dia de atua\u00e7\u00e3o presencial no escrit\u00f3rio. No entanto, entendemos que era necess\u00e1rio um maior controle para evitar o overbooking, impedindo que o colaborador chegasse e n\u00e3o encontrasse um lugar fixo para trabalhar, o que comprometia seu senso de pertencimento<\/em>\u201d, afirma Marta Bezerra, gerente de opera\u00e7\u00f5es da Webmotors.<\/p>\n<p>A tecnologia adotada, baseada no HID Identity Positioning, permite identificar, em tempo real, a ocupa\u00e7\u00e3o dos ambientes internos indicando quem est\u00e1 utilizando os espa\u00e7os, onde e quando. Integrada aos sistemas existentes e \u00e0 plataforma Deskbee, a solu\u00e7\u00e3o viabiliza o monitoramento cont\u00ednuo da ocupa\u00e7\u00e3o, contribuindo para decis\u00f5es mais estrat\u00e9gicas sobre o uso do escrit\u00f3rio, al\u00e9m de promover ganhos em efici\u00eancia operacional e sustentabilidade.<\/p>\n<p>\u201c<em>O grande desafio da implementa\u00e7\u00e3o foi alinhar expectativas do ponto de vista do que faz sentido para uma solu\u00e7\u00e3o. Um cliente que hoje adere \u00e0 Deskbee como plataforma de gerenciamento de espa\u00e7o de trabalho tem o benef\u00edcio da expertise em identidades seguras da HID, garantindo acesso seguro, informa\u00e7\u00e3o de presen\u00e7a e ocupa\u00e7\u00e3o em tempo real\u201d<\/em>, destaca Ricardo Vernizzi, Regional Product Marketing Director da HID.<\/p>\n<p>Para os colaboradores, a experi\u00eancia tamb\u00e9m foi aprimorada. O sistema funciona com check-in autom\u00e1tico a partir da reserva dos espa\u00e7os, registrando a presen\u00e7a de forma integrada e eliminando processos manuais. \u201c<em>Essa tecnologia facilita para que os colaboradores tenham uma melhor experi\u00eancia na chegada, com seu check-in autom\u00e1tico. Quando eles fazem uma reserva do espa\u00e7o de trabalho, ela \u00e9 capturada de forma autom\u00e1tica e alimenta os dados de ocupa\u00e7\u00e3o. Para os gestores, isso traz a assertividade de que a presen\u00e7a e a ocupa\u00e7\u00e3o est\u00e3o sendo capturadas em tempo real<\/em>\u201d, explica Fernando Gorguet, Head Global Sales da Deskbee.<\/p>\n<p>Com a iniciativa, a Webmotors refor\u00e7a seu compromisso com a inova\u00e7\u00e3o e com a constru\u00e7\u00e3o de um ambiente de trabalho mais eficiente, conectado e centrado nas pessoas. \u201c<em>Todos os dias em que a gente traz uma mudan\u00e7a para o colaborador, ele se sente mais pertencente e trabalha com mais qualidade e produtividade\u201d<\/em>, conclui Marta Bezerra.<\/p>\n<p><a title=\"https:\/\/hid.link\/webmotors\" href=\"https:\/\/hid.link\/webmotors\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"0\">Assista ao v\u00eddeo<\/a>\u00a0e veja como a tecnologia HID est\u00e1 transformando a experi\u00eancia dos colaboradores da Webmotors.<\/p>\n<p><strong>Fique conectado com a HID<\/strong><\/p>\n<p>Visite nosso\u00a0<a title=\"https:\/\/www.hidglobal.com\/main\/media-center\/\" href=\"https:\/\/www.hidglobal.com\/main\/media-center\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"1\">Centro de m\u00eddia<\/a>, leia nosso\u00a0<a title=\"https:\/\/blog.hidglobal.com\/es\" href=\"https:\/\/blog.hidglobal.com\/es\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"2\">blog do setor<\/a>\u00a0e siga-nos no\u00a0<a title=\"https:\/\/www.facebook.com\/hidglobalespanol\/\" href=\"https:\/\/www.facebook.com\/hidglobalespanol\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"3\">Facebook<\/a>,\u00a0<a title=\"https:\/\/twitter.com\/HID_espanol\" href=\"https:\/\/twitter.com\/HID_espanol\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"4\">Twitter<\/a>\u00a0e\u00a0<a title=\"https:\/\/www.linkedin.com\/showcase\/6451483\/\" href=\"https:\/\/www.linkedin.com\/showcase\/6451483\/\" target=\"_blank\" rel=\"noreferrer noopener\" shape=\"rect\" data-auth=\"NotApplicable\" data-linkindex=\"5\">LinkedIn<\/a>.<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>Sobre a Webmotors<\/strong><br clear=\"none\" \/>H\u00e1 mais de 20 anos na estrada, a Webmotors foi a primeira startup brasileira a inovar na forma de comprar e vender carros e motos. L\u00edderes de mercado e especialistas no segmento, a empresa tem como combust\u00edvel a paix\u00e3o pela cultura automotiva e a vontade de oferecer sempre a melhor e mais segura experi\u00eancia de compra e venda online.<\/p>\n<p aria-hidden=\"true\">\u00a0<\/p>\n<p><strong>Sobre a HID<\/strong><\/p>\n<p>A HID fornece a tecnologia que suporta identidades seguras de pessoas, lugares e objetos em todo o mundo. Tornamos poss\u00edvel que as pessoas realizem transa\u00e7\u00f5es seguras, trabalhem de forma produtiva e viajem com liberdade. Nossas solu\u00e7\u00f5es de identifica\u00e7\u00e3o segura permitem que as\u00a0pessoas\u00a0acessem com comodidade e seguran\u00e7a\u00a0locais\u00a0f\u00edsicos e digitais e conectem\u00a0objetosque podem ser identificados com precis\u00e3o, verificados e rastreados digitalmente. Milh\u00f5es de pessoas em todo o mundo utilizam os produtos e servi\u00e7os da HID em suas vidas di\u00e1rias, e bilh\u00f5es de objetos est\u00e3o conectados por meio da tecnologia da HID. Trabalhamos com governos, institui\u00e7\u00f5es educacionais, hospitais, institui\u00e7\u00f5es financeiras, empresas industriais e algumas das empresas mais inovadoras do planeta. Com sede em Austin, Texas, a HID tem mais de 4.000 funcion\u00e1rios em todo o mundo e opera escrit\u00f3rios internacionais que prestam suporte a mais de 100 pa\u00edses. A HID\u00ae \u00e9 uma empresa do grupo ASSA ABLOY. Para obter mais informa\u00e7\u00f5es, visite https:\/\/www.hidglobal.com\/es<\/p>\n<p># # #<\/p>\n<p>\u00a9 2026 HID Global Corporation\/ASSA ABLOY AB. Todos os direitos reservados. HID, o logotipo azul da HID e o design em cadeia, HID Signo, HID Origo, HID Mobile Access e iClass Seos s\u00e3o marcas comerciais ou marcas registradas da HID Global, ASSA ABLOY AB ou suas subsidi\u00e1rias nos Estados Unidos e em outros pa\u00edses, e n\u00e3o podem ser usados sem autoriza\u00e7\u00e3o. Todas as outras marcas comerciais, marcas de servi\u00e7o e nomes de produtos ou servi\u00e7os s\u00e3o marcas comerciais ou marcas registradas de seus respectivos propriet\u00e1rios.<\/p>\n<hr \/>\n<h6><strong>Tr\u00f3pico Comunica\u00e7\u00e3o<\/strong><\/h6>\n<\/div>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Solu\u00e7\u00e3o combina dados em tempo real e credenciais m\u00f3veis para otimizar a ocupa\u00e7\u00e3o e a rotina dos colaboradores Fundada h\u00e1 30 anos, a Webmotors, uma das principais plataformas digitais do setor automotivo, vem consolidando sua atua\u00e7\u00e3o na intermedia\u00e7\u00e3o de compra, venda e servi\u00e7os relacionados a ve\u00edculos. Nascida no contexto da digitaliza\u00e7\u00e3o dos classificados impressos, a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-84601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/84601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=84601"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/84601\/revisions"}],"predecessor-version":[{"id":84603,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/84601\/revisions\/84603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/84602"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=84601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=84601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=84601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}