{"id":84645,"date":"2026-05-06T14:18:50","date_gmt":"2026-05-06T17:18:50","guid":{"rendered":"http:\/\/sol.fm.br\/radio\/?p=84645"},"modified":"2026-05-06T14:18:54","modified_gmt":"2026-05-06T17:18:54","slug":"cavalo-crioulo-e-presenca-confirmada-no-mundial-paraequestre-na-alemanha","status":"publish","type":"post","link":"https:\/\/sol.fm.br\/radio\/cavalo-crioulo-e-presenca-confirmada-no-mundial-paraequestre-na-alemanha\/","title":{"rendered":"Cavalo Crioulo \u00e9 presen\u00e7a confirmada no Mundial Paraequestre na Alemanha"},"content":{"rendered":"<div id=\"dslc-theme-content\"><div id=\"dslc-theme-content-inner\"><p dir=\"ltr\"><span data-olk-copy-source=\"MessageBody\">O time brasileiro de Paradestramento nos Jogos Equestres Mundiais 2026, em Aachen, na Alemanha, compete com o Cavalo Crioulo Fronterizo da El Comandante. Em conjunto com o cavaleiro paranaense, Cleberson Antunes Palhano, o cavalo\u00a0 atingiu 1.191 pontos ao longo das classificat\u00f3rias e a dupla \u00e9 uma das quatro brasileiras na competi\u00e7\u00e3o que classifica para as Ol\u00edmpiadas de 2028.\u00a0<\/span><\/p>\n<p dir=\"ltr\">Palhano \u00e9 o 6\u00ba melhor cavaleiro do mundo no Grau I de Adestramento Paraequestre. Sua Fronterizo da El Comandante come\u00e7ou h\u00e1 pouco mais de um ano e o conjunto j\u00e1 foi campe\u00e3o brasileiro em 2025. Palhano come\u00e7ou a participar de atividades equestres h\u00e1 quase duas d\u00e9cadas, a partir da integra\u00e7\u00e3o na Associa\u00e7\u00e3o Paranaense de Equoterapia e Inclus\u00e3o Equestre (APEIE), em Ponta Grossa (PR). \u201c<em>Ele veio com o objetivo de adquirir mais for\u00e7a, equil\u00edbrio e coordena\u00e7\u00e3o motora\u201d<\/em>, lembra o diretor Paraequestre da Federa\u00e7\u00e3o Paranaense de Hipismo, Eros Spartalis. A partir de 2011, o atleta iniciou a jornada no esporte na modalidade de Paraenduro e em 2022, come\u00e7ou no Adestramento Paraequestre. <em>\u201cA conquista \u00e9 um feito in\u00e9dito para a ra\u00e7a Crioula. Com certeza, foi formado um conjunto de muita qualidade<\/em>\u201d, aponta Spartalis.\u00a0<\/p>\n<p dir=\"ltr\">Animado, o cavaleiro comemora a conquista e destaca a import\u00e2ncia da equoterapia para as pessoas com defici\u00eancia. \u201c<em>Para n\u00f3s, faz toda a diferen\u00e7a. Cada evolu\u00e7\u00e3o proporcionada pelo tratamento representa uma transforma\u00e7\u00e3o significativa na qualidade de vida. Fico muito feliz de ter chegado at\u00e9 aqui e poder celebrar essa conquista\u201d<\/em>, destaca o atleta, que nasceu com paralisia cerebral. A competi\u00e7\u00e3o em Aachen ocorre entre os dias 11 e 23 de agosto, no Allianz Park, e \u00e9 o evento m\u00e1ximo organizado pela Federa\u00e7\u00e3o Equestre Internacional. A disputa re\u00fane as principais modalidades do esporte, incluindo salto, adestramento, concurso completo, atrelagem, volteio e r\u00e9deas.\u00a0<\/p>\n<hr \/>\n<h6 dir=\"ltr\"><strong>Jard!ne Ag\u00eancia de comunica\u00e7\u00e3o | Foto: Clauder Valim Carriel<\/strong><\/h6>\n\n\n<center><iframe loading=\"lazy\" class=\"jmvplayer\" src=\"https:\/\/player.jmvstream.com\/lvw\/YYGWo5wfZuZ8fEW7Qoq1ISwhLSEDhU\" allowfullscreen allow=\"autoplay; fullscreen\" frameborder=\"0\" width=\"640\" height=\"360\" ><\/iframe><\/center>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O time brasileiro de Paradestramento nos Jogos Equestres Mundiais 2026, em Aachen, na Alemanha, compete com o Cavalo Crioulo Fronterizo da El Comandante. Em conjunto com o cavaleiro paranaense, Cleberson Antunes Palhano, o cavalo\u00a0 atingiu 1.191 pontos ao longo das classificat\u00f3rias e a dupla \u00e9 uma das quatro brasileiras na competi\u00e7\u00e3o que classifica para as [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":84646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-84645","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/84645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/comments?post=84645"}],"version-history":[{"count":1,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/84645\/revisions"}],"predecessor-version":[{"id":84647,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/posts\/84645\/revisions\/84647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media\/84646"}],"wp:attachment":[{"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/media?parent=84645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/categories?post=84645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sol.fm.br\/radio\/wp-json\/wp\/v2\/tags?post=84645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}